{"id":467,"date":"2018-08-16T00:00:00","date_gmt":"2018-08-15T15:00:00","guid":{"rendered":"https:\/\/dgloss.co.jp\/wp\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2"},"modified":"2018-08-16T00:00:00","modified_gmt":"2018-08-15T15:00:00","slug":"%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2","status":"publish","type":"portfolios","link":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2\/","title":{"rendered":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc\u30d3\u30b9\u4f1a\u793e\u2461 \u69d8"},"content":{"rendered":"<p>\u4f9d\u983c\u5185\u5bb9<\/p>\n<p>\u25a0\u5f93\u696d\u54e1\u6570\uff1a\u554f\u308f\u305a<br \/>\u25a0\u696d\u7a2e\uff1a\u4e8b\u52d9\u8077\u30fb\u30d0\u30c3\u30af\u30aa\u30d5\u30a3\u30b9\u696d\u52d9<br \/>\u25a0\u5730\u57df\uff1a\u798f\u5ca1\u770c\u5185<br \/>\u25a0\u6708\u9593\u30a2\u30dd\u30a4\u30f3\u30c8\u4ef6\u6570\uff1a10\u4ef6<\/p>\n<p>\u3010\u30a2\u30dd\u30a4\u30f3\u30c8\u5185\u5bb9\u3011<\/p>\n<p>\u696d\u7a2e\u554f\u308f\u305a\u4e8b\u52d9\u8077\u30fb\u30d0\u30c3\u30af\u30aa\u30d5\u30a3\u30b9\u696d\u52d9\u3067\u306e\u4eba\u6750\u6d3e\u9063\u306e\u3054\u63d0\u6848\u3092\u884c\u3046\u3002<br \/>\u6d3e\u9063\u3067\u73fe\u5728\u52df\u96c6\u4e2d\u3067\u3042\u308b\u4e8b\u3002<br \/>\u6d3e\u9063\u6599\u91d1\u306e\u57fa\u672c\u6599\u91d1\u3092\u304a\u4f1d\u3048\u3057\u3001\u4e86\u627f\u3092\u5f97\u3066\u3044\u308b\u4e8b\u3002<\/p>\n<p>\u30a2\u30dd\u7387\uff1a\uff13.1\uff05<br \/>\u30a2\u30dd\u30a4\u30f3\u30c8\u6570\uff1a20\u4ef6\uff08\u73fe\u5728\u7a3c\u50cd\u4e2d\uff09<br \/>\u5b9f\u7e3e\uff1a15\u793e \u898b\u8fbc\uff1a2\u793e<\/p>\n","protected":false},"featured_media":0,"template":"","portfolios-cat":[],"portfolios-tag":[],"class_list":["post-467","portfolios","type-portfolios","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc\u30d3\u30b9\u4f1a\u793e\u2461 \u69d8 - DGLOSS Co., Ltd<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc\u30d3\u30b9\u4f1a\u793e\u2461 \u69d8 - DGLOSS Co., Ltd\" \/>\n<meta property=\"og:description\" content=\"\u4f9d\u983c\u5185\u5bb9 \u25a0\u5f93\u696d\u54e1\u6570\uff1a\u554f\u308f\u305a\u25a0\u696d\u7a2e\uff1a\u4e8b\u52d9\u8077\u30fb\u30d0\u30c3\u30af\u30aa\u30d5\u30a3\u30b9\u696d\u52d9\u25a0\u5730\u57df\uff1a\u798f\u5ca1\u770c\u5185\u25a0\u6708\u9593\u30a2\u30dd\u30a4\u30f3\u30c8\u4ef6\u6570\uff1a10\u4ef6 \u3010\u30a2\u30dd\u30a4\u30f3\u30c8\u5185\u5bb9\u3011 \u696d\u7a2e\u554f\u308f\u305a\u4e8b\u52d9\u8077\u30fb\u30d0\u30c3\u30af\u30aa\u30d5\u30a3\u30b9\u696d\u52d9\u3067\u306e\u4eba\u6750\u6d3e\u9063\u306e\u3054\u63d0\u6848\u3092\u884c\u3046\u3002\u6d3e\u9063\u3067\u73fe\u5728\u52df\u96c6\u4e2d\u3067\u3042\u308b\u4e8b\u3002\u6d3e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc-2\/\" \/>\n<meta property=\"og:site_name\" content=\"DGLOSS Co., Ltd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2\/\",\"url\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2\/\",\"name\":\"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc\u30d3\u30b9\u4f1a\u793e\u2461 \u69d8 - DGLOSS Co., Ltd\",\"isPartOf\":{\"@id\":\"https:\/\/dgloss.co.jp\/#website\"},\"datePublished\":\"2018-08-15T15:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dgloss.co.jp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30a2\u30dd\u30d7\u30ed\",\"item\":\"\/tele-appointment\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u652f\u63f4\u5b9f\u7e3e\",\"item\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc\u30d3\u30b9\u4f1a\u793e\u2461 \u69d8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dgloss.co.jp\/#website\",\"url\":\"https:\/\/dgloss.co.jp\/\",\"name\":\"DGLOSS Co., Ltd\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dgloss.co.jp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc\u30d3\u30b9\u4f1a\u793e\u2461 \u69d8 - DGLOSS Co., Ltd","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc-2\/","og_locale":"en_US","og_type":"article","og_title":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc\u30d3\u30b9\u4f1a\u793e\u2461 \u69d8 - DGLOSS Co., Ltd","og_description":"\u4f9d\u983c\u5185\u5bb9 \u25a0\u5f93\u696d\u54e1\u6570\uff1a\u554f\u308f\u305a\u25a0\u696d\u7a2e\uff1a\u4e8b\u52d9\u8077\u30fb\u30d0\u30c3\u30af\u30aa\u30d5\u30a3\u30b9\u696d\u52d9\u25a0\u5730\u57df\uff1a\u798f\u5ca1\u770c\u5185\u25a0\u6708\u9593\u30a2\u30dd\u30a4\u30f3\u30c8\u4ef6\u6570\uff1a10\u4ef6 \u3010\u30a2\u30dd\u30a4\u30f3\u30c8\u5185\u5bb9\u3011 \u696d\u7a2e\u554f\u308f\u305a\u4e8b\u52d9\u8077\u30fb\u30d0\u30c3\u30af\u30aa\u30d5\u30a3\u30b9\u696d\u52d9\u3067\u306e\u4eba\u6750\u6d3e\u9063\u306e\u3054\u63d0\u6848\u3092\u884c\u3046\u3002\u6d3e\u9063\u3067\u73fe\u5728\u52df\u96c6\u4e2d\u3067\u3042\u308b\u4e8b\u3002\u6d3e [&hellip;]","og_url":"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc-2\/","og_site_name":"DGLOSS Co., Ltd","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2\/","url":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2\/","name":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc\u30d3\u30b9\u4f1a\u793e\u2461 \u69d8 - DGLOSS Co., Ltd","isPartOf":{"@id":"https:\/\/dgloss.co.jp\/#website"},"datePublished":"2018-08-15T15:00:00+00:00","breadcrumb":{"@id":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e4%ba%ba%e6%9d%90%e6%b4%be%e9%81%a3%e3%82%b5%e3%83%bc-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dgloss.co.jp\/"},{"@type":"ListItem","position":2,"name":"\u30a2\u30dd\u30d7\u30ed","item":"\/tele-appointment\/"},{"@type":"ListItem","position":3,"name":"\u652f\u63f4\u5b9f\u7e3e","item":"https:\/\/dgloss.co.jp\/en\/portfolios\/"},{"@type":"ListItem","position":4,"name":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u4eba\u6750\u6d3e\u9063\u30b5\u30fc\u30d3\u30b9\u4f1a\u793e\u2461 \u69d8"}]},{"@type":"WebSite","@id":"https:\/\/dgloss.co.jp\/#website","url":"https:\/\/dgloss.co.jp\/","name":"DGLOSS Co., Ltd","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dgloss.co.jp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios\/467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios"}],"about":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/types\/portfolios"}],"wp:attachment":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/media?parent=467"}],"wp:term":[{"taxonomy":"portfolios-cat","embeddable":true,"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios-cat?post=467"},{"taxonomy":"portfolios-tag","embeddable":true,"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios-tag?post=467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}