{"id":5274,"date":"2023-10-20T10:42:06","date_gmt":"2023-10-20T01:42:06","guid":{"rendered":"https:\/\/dgloss.co.jp\/?post_type=portfolios&#038;p=5274"},"modified":"2023-10-20T10:42:50","modified_gmt":"2023-10-20T01:42:50","slug":"%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba","status":"publish","type":"portfolios","link":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba\/","title":{"rendered":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\u5a92\u4f53\u63b2\u8f09\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e\u69d8"},"content":{"rendered":"\n<p>\u73fe\u5728\u3001\u82e5\u624b\u4eba\u6750\u63a1\u7528\u52df\u96c6\u4e2d\u3082\u3057\u304f\u306f\u76f4\u8fd1\u3067\u63a1\u7528\u8a08\u753b\u304c\u3042\u308b\u4f01\u696d\u69d8\u306b\u5bfe\u3057\u3001\u5e0c\u671b\u30a8\u30ea\u30a2\u3084\u8077\u7a2e\u3001\u63a1\u7528\u8ab2\u984c\u306a\u3069\u3092\u30d2\u30a2\u30ea\u30f3\u30b0\u3057\u3064\u3064\u3001\u82e5\u5e74\u5c64\u306e\u6d41\u5165\u3092\u5897\u3084\u3059\u5e83\u544a\u904b\u7528\u3084\u6d41\u5165\u7d4c\u8def\u306e\u63d0\u6848\u3068\u5171\u306b\u3001\u4ed6\u793e\u6d3b\u7528\u4e8b\u4f8b\u306a\u3069\u3092\u7d39\u4ecb\u3057\u3001\u5546\u8ac7\u30a2\u30dd\u30a4\u30f3\u30c8\u3092\u30c6\u30ec\u30a2\u30dd\u55b6\u696d\u4ee3\u884c\u306b\u3066\u7372\u5f97\u3002<\/p>\n\n\n\n<p>\u3010\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\u5185\u5bb9\u3011<br>\u25a0\u30c6\u30ec\u30a2\u30dd\u30a8\u30ea\u30a2\uff1a\u5168\u56fd<br>\u25a0\u6708\u9593\u30a2\u30dd\u30a4\u30f3\u30c8\u4ef6\u6570\uff1a20\u4ef6<br>\u25a0\u6761\u4ef6\uff1a<br>\u30fb\u82e5\u624b\u4eba\u6750\u63a1\u7528\u3082\u3057\u304f\u306f\u5b66\u6b74\u4e0d\u554f\u6c42\u4eba\u3092\u5b9f\u65bd\u4e2d\u306e\u4f01\u696d<br>\u30fb\u63a1\u7528\u8ab2\u984c\u304c\u3042\u308a\u3001\u4e88\u7b97\u3092\u304b\u3051\u305f\u6c42\u4eba\u65bd\u7b56\u3092\u5b9f\u65bd\u691c\u8a0e\u53ef\u80fd\u306a\u3053\u3068<\/p>\n\n\n\n<p>\u30c6\u30ec\u30a2\u30dd\u7387\uff1a2.6\uff05<br>\u30a2\u30dd\u30a4\u30f3\u30c8\u6570\uff1a40\u4ef6<br>\u6848\u4ef6\u53d7\u6ce8\uff1a15\u4ef6<\/p>\n","protected":false},"featured_media":0,"template":"","portfolios-cat":[],"portfolios-tag":[],"class_list":["post-5274","portfolios","type-portfolios","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\u5a92\u4f53\u63b2\u8f09\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e\u69d8 - DGLOSS Co., Ltd<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\u5a92\u4f53\u63b2\u8f09\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e\u69d8 - DGLOSS Co., Ltd\" \/>\n<meta property=\"og:description\" content=\"\u73fe\u5728\u3001\u82e5\u624b\u4eba\u6750\u63a1\u7528\u52df\u96c6\u4e2d\u3082\u3057\u304f\u306f\u76f4\u8fd1\u3067\u63a1\u7528\u8a08\u753b\u304c\u3042\u308b\u4f01\u696d\u69d8\u306b\u5bfe\u3057\u3001\u5e0c\u671b\u30a8\u30ea\u30a2\u3084\u8077\u7a2e\u3001\u63a1\u7528\u8ab2\u984c\u306a\u3069\u3092\u30d2\u30a2\u30ea\u30f3\u30b0\u3057\u3064\u3064\u3001\u82e5\u5e74\u5c64\u306e\u6d41\u5165\u3092\u5897\u3084\u3059\u5e83\u544a\u904b\u7528\u3084\u6d41\u5165\u7d4c\u8def\u306e\u63d0\u6848\u3068\u5171\u306b\u3001\u4ed6\u793e\u6d3b\u7528\u4e8b\u4f8b\u306a\u3069\u3092\u7d39\u4ecb\u3057\u3001\u5546\u8ac7\u30a2\u30dd\u30a4\u30f3\u30c8\u3092\u30c6\u30ec\u30a2\u30dd\u55b6 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\/\" \/>\n<meta property=\"og:site_name\" content=\"DGLOSS Co., Ltd\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-20T01:42:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba\/\",\"url\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba\/\",\"name\":\"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\u5a92\u4f53\u63b2\u8f09\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e\u69d8 - DGLOSS Co., Ltd\",\"isPartOf\":{\"@id\":\"https:\/\/dgloss.co.jp\/#website\"},\"datePublished\":\"2023-10-20T01:42:06+00:00\",\"dateModified\":\"2023-10-20T01:42:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dgloss.co.jp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30a2\u30dd\u30d7\u30ed\",\"item\":\"\/tele-appointment\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u652f\u63f4\u5b9f\u7e3e\",\"item\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\u5a92\u4f53\u63b2\u8f09\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e\u69d8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dgloss.co.jp\/#website\",\"url\":\"https:\/\/dgloss.co.jp\/\",\"name\":\"DGLOSS Co., Ltd\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dgloss.co.jp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\u5a92\u4f53\u63b2\u8f09\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e\u69d8 - DGLOSS Co., Ltd","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\/","og_locale":"en_US","og_type":"article","og_title":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\u5a92\u4f53\u63b2\u8f09\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e\u69d8 - DGLOSS Co., Ltd","og_description":"\u73fe\u5728\u3001\u82e5\u624b\u4eba\u6750\u63a1\u7528\u52df\u96c6\u4e2d\u3082\u3057\u304f\u306f\u76f4\u8fd1\u3067\u63a1\u7528\u8a08\u753b\u304c\u3042\u308b\u4f01\u696d\u69d8\u306b\u5bfe\u3057\u3001\u5e0c\u671b\u30a8\u30ea\u30a2\u3084\u8077\u7a2e\u3001\u63a1\u7528\u8ab2\u984c\u306a\u3069\u3092\u30d2\u30a2\u30ea\u30f3\u30b0\u3057\u3064\u3064\u3001\u82e5\u5e74\u5c64\u306e\u6d41\u5165\u3092\u5897\u3084\u3059\u5e83\u544a\u904b\u7528\u3084\u6d41\u5165\u7d4c\u8def\u306e\u63d0\u6848\u3068\u5171\u306b\u3001\u4ed6\u793e\u6d3b\u7528\u4e8b\u4f8b\u306a\u3069\u3092\u7d39\u4ecb\u3057\u3001\u5546\u8ac7\u30a2\u30dd\u30a4\u30f3\u30c8\u3092\u30c6\u30ec\u30a2\u30dd\u55b6 [&hellip;]","og_url":"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\/","og_site_name":"DGLOSS Co., Ltd","article_modified_time":"2023-10-20T01:42:50+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba\/","url":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba\/","name":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\u5a92\u4f53\u63b2\u8f09\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e\u69d8 - DGLOSS Co., Ltd","isPartOf":{"@id":"https:\/\/dgloss.co.jp\/#website"},"datePublished":"2023-10-20T01:42:06+00:00","dateModified":"2023-10-20T01:42:50+00:00","breadcrumb":{"@id":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91%e7%ac%ac%e4%ba%8c%e6%96%b0%e5%8d%92%e6%b1%82%e4%ba%ba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dgloss.co.jp\/"},{"@type":"ListItem","position":2,"name":"\u30a2\u30dd\u30d7\u30ed","item":"\/tele-appointment\/"},{"@type":"ListItem","position":3,"name":"\u652f\u63f4\u5b9f\u7e3e","item":"https:\/\/dgloss.co.jp\/en\/portfolios\/"},{"@type":"ListItem","position":4,"name":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011\u7b2c\u4e8c\u65b0\u5352\u6c42\u4eba\u5a92\u4f53\u63b2\u8f09\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e\u69d8"}]},{"@type":"WebSite","@id":"https:\/\/dgloss.co.jp\/#website","url":"https:\/\/dgloss.co.jp\/","name":"DGLOSS Co., Ltd","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dgloss.co.jp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios\/5274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios"}],"about":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/types\/portfolios"}],"wp:attachment":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/media?parent=5274"}],"wp:term":[{"taxonomy":"portfolios-cat","embeddable":true,"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios-cat?post=5274"},{"taxonomy":"portfolios-tag","embeddable":true,"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios-tag?post=5274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}