{"id":530,"date":"2020-01-30T00:00:00","date_gmt":"2020-01-29T15:00:00","guid":{"rendered":"https:\/\/dgloss.co.jp\/wp\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3"},"modified":"2020-01-30T00:00:00","modified_gmt":"2020-01-29T15:00:00","slug":"%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3","status":"publish","type":"portfolios","link":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3\/","title":{"rendered":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011 \u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e \u69d8"},"content":{"rendered":"<div dir=\"ltr\">\n<div>\u3010\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\u5185\u5bb9\u3011<br \/>\u5bb6\u96fb\u30fb\u5bb6\u5177\u30fb\u5f15\u8d8a\u30fb<wbr \/>\u4f4f\u5b85\u306a\u3069\u751f\u6d3b\u306b\u95a2\u9023\u3057\u305f\u5546\u54c1\u306e\u6709\u540d\u4eba\u6c17\u6bd4\u8f03\u8a18\u4e8b<span class=\"il\">\u30b5\u30a4\u30c8<\/span>\u7d0430\u30b5\u30a4<wbr \/>\u30c8\u306b\u8a2a\u308c\u305f\u9867\u5ba2\u306b\u306a\u308a\u5f97\u308b\u53ef\u80fd\u6027\u304c\u9ad8\u3044\u30e6\u30fc\u30b6\u30fc\u306e\u307f\u306b\u9650\u5b9a\u3057\u3066\u5e83\u544a\u914d\u4fe1\u304c\u3067\u304d\u308b\u72ec\u81ea\u306e\u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3<wbr \/>\u30b9\u3092\u3001<wbr \/>\u5bb6\u96fb\u3084\u5bb6\u5177\u306a\u3069\u306e\u88fd\u9020\u3092\u884c\u3063\u3066\u3044\u308b\u30e1\u30fc\u30ab\u30fc\u4f01\u696d\u306a\u3069\u306b\u5bfe\u3057\u3001Web\u30d7\u30ed\u30e2\u30fc\u30b7\u30e7\u30f3\u5b9f\u65bd\u6709\u7121\u306e\u30d2\u30a2\u30ea\u30f3\u30b0\u3092\u884c\u3063\u305f\u4e0a\u3067\u3001<wbr \/>\u4ed6\u30d7\u30ed\u30e2\u30fc\u30b7\u30e7\u30f3\u3068\u306e\u6bd4\u8f03\uff08\u52b9\u679c\u3001\u30b3\u30b9\u30c8\u30e1\u30ea\u30c3\u30c8\u306a\u3069\uff09\u3084\u3001<wbr \/>\u4ed6\u793e\u4e8b\u4f8b\u306a\u3069\u3092\u8a34\u6c42\u3057\u3001\u5546\u8ac7\u30a2\u30dd\u30a4\u30f3\u30c8\u3092\u30c6\u30ec\u30a2\u30dd\u55b6\u696d\u4ee3\u884c\u306b\u3066\u7372\u5f97\u3002<\/div>\n<\/div>\n<div dir=\"ltr\">\n<div>\u00a0<\/div>\n<div>\u25a0\u30c6\u30ec\u30a2\u30dd\u30a8\u30ea\u30a2\uff1a<br \/>\u5168\u56fd\uff08\u5317\u6d77\u9053\u3001\u6c96\u7e04\u3092\u9664\u304f\uff09<\/div>\n<div>\u00a0<\/div>\n<div>\u25a0\u6708\u9593\u30a2\u30dd\u30a4\u30f3\u30c8\u4ef6\u6570\uff1a20\u4ef6<\/div>\n<div>\u00a0<\/div>\n<div>\u25a0\u6761\u4ef6\uff1a<\/div>\n<div>\u30fb<wbr \/>\u6708\u9593Web\u5e83\u544a\u4e88\u7b9750\u4e07\u5186\u4ee5\u4e0a\u306e\u65bd\u7b56\u5c0e\u5165\u304c\u691c\u8a0e\u3067\u304d\u308b\u4f01\u696d\u3067\u3042<wbr \/>\u308b\u3053\u3068<\/div>\n<div>\u30fbWeb\u5e83\u544a\u3092\u884c\u3063\u3066\u3044\u308b\u3053\u3068<\/div>\n<div>\u00a0<\/div>\n<div>\u30c6\u30ec\u30a2\u30dd\u7387\uff1a4.4\uff05<br \/>\u30a2\u30dd\u30a4\u30f3\u30c8\u6570\uff1a67\u4ef6\uff08\u73fe\u72b6\u7a3c\u50cd\u4e2d\uff09<br \/>\u6848\u4ef6\u53d7\u6ce8\uff1a33\u793e\u3000\u203b\u4ed6\u53d7\u6ce8\u898b\u8fbc5\u793e\u3042\u308a<\/div>\n<\/div>\n","protected":false},"featured_media":0,"template":"","portfolios-cat":[],"portfolios-tag":[],"class_list":["post-530","portfolios","type-portfolios","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011 \u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e \u69d8 - DGLOSS Co., Ltd<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011-\u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011 \u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e \u69d8 - DGLOSS Co., Ltd\" \/>\n<meta property=\"og:description\" content=\"\u3010\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\u5185\u5bb9\u3011\u5bb6\u96fb\u30fb\u5bb6\u5177\u30fb\u5f15\u8d8a\u30fb\u4f4f\u5b85\u306a\u3069\u751f\u6d3b\u306b\u95a2\u9023\u3057\u305f\u5546\u54c1\u306e\u6709\u540d\u4eba\u6c17\u6bd4\u8f03\u8a18\u4e8b\u30b5\u30a4\u30c8\u7d0430\u30b5\u30a4\u30c8\u306b\u8a2a\u308c\u305f\u9867\u5ba2\u306b\u306a\u308a\u5f97\u308b\u53ef\u80fd\u6027\u304c\u9ad8\u3044\u30e6\u30fc\u30b6\u30fc\u306e\u307f\u306b\u9650\u5b9a\u3057\u3066\u5e83\u544a\u914d\u4fe1\u304c\u3067\u304d\u308b\u72ec\u81ea\u306e\u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3\u30b9\u3092\u3001\u5bb6\u96fb\u3084 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011-\u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\/\" \/>\n<meta property=\"og:site_name\" content=\"DGLOSS Co., Ltd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3\/\",\"url\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3\/\",\"name\":\"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011 \u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e \u69d8 - DGLOSS Co., Ltd\",\"isPartOf\":{\"@id\":\"https:\/\/dgloss.co.jp\/#website\"},\"datePublished\":\"2020-01-29T15:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dgloss.co.jp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30a2\u30dd\u30d7\u30ed\",\"item\":\"\/tele-appointment\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u652f\u63f4\u5b9f\u7e3e\",\"item\":\"https:\/\/dgloss.co.jp\/en\/portfolios\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011 \u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e \u69d8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dgloss.co.jp\/#website\",\"url\":\"https:\/\/dgloss.co.jp\/\",\"name\":\"DGLOSS Co., Ltd\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dgloss.co.jp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011 \u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e \u69d8 - DGLOSS Co., Ltd","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011-\u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\/","og_locale":"en_US","og_type":"article","og_title":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011 \u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e \u69d8 - DGLOSS Co., Ltd","og_description":"\u3010\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\u5185\u5bb9\u3011\u5bb6\u96fb\u30fb\u5bb6\u5177\u30fb\u5f15\u8d8a\u30fb\u4f4f\u5b85\u306a\u3069\u751f\u6d3b\u306b\u95a2\u9023\u3057\u305f\u5546\u54c1\u306e\u6709\u540d\u4eba\u6c17\u6bd4\u8f03\u8a18\u4e8b\u30b5\u30a4\u30c8\u7d0430\u30b5\u30a4\u30c8\u306b\u8a2a\u308c\u305f\u9867\u5ba2\u306b\u306a\u308a\u5f97\u308b\u53ef\u80fd\u6027\u304c\u9ad8\u3044\u30e6\u30fc\u30b6\u30fc\u306e\u307f\u306b\u9650\u5b9a\u3057\u3066\u5e83\u544a\u914d\u4fe1\u304c\u3067\u304d\u308b\u72ec\u81ea\u306e\u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3\u30b9\u3092\u3001\u5bb6\u96fb\u3084 [&hellip;]","og_url":"https:\/\/dgloss.co.jp\/en\/portfolios\/\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011-\u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\/","og_site_name":"DGLOSS Co., Ltd","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3\/","url":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3\/","name":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011 \u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e \u69d8 - DGLOSS Co., Ltd","isPartOf":{"@id":"https:\/\/dgloss.co.jp\/#website"},"datePublished":"2020-01-29T15:00:00+00:00","breadcrumb":{"@id":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dgloss.co.jp\/en\/portfolios\/%e3%80%90%e5%96%b6%e6%a5%ad%e4%bb%a3%e8%a1%8c%ef%bc%88%e3%83%86%e3%83%ac%e3%82%a2%e3%83%9d%e4%bb%a3%e8%a1%8c%ef%bc%89%e4%ba%8b%e4%be%8b%e3%80%91-%e3%83%aa%e3%82%bf%e3%83%bc%e3%82%b2%e3%83%86%e3%82%a3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dgloss.co.jp\/"},{"@type":"ListItem","position":2,"name":"\u30a2\u30dd\u30d7\u30ed","item":"\/tele-appointment\/"},{"@type":"ListItem","position":3,"name":"\u652f\u63f4\u5b9f\u7e3e","item":"https:\/\/dgloss.co.jp\/en\/portfolios\/"},{"@type":"ListItem","position":4,"name":"\u3010\u55b6\u696d\u4ee3\u884c\uff08\u30c6\u30ec\u30a2\u30dd\u4ee3\u884c\uff09\u4e8b\u4f8b\u3011 \u30ea\u30bf\u30fc\u30b2\u30c6\u30a3\u30f3\u30b0\u5e83\u544a\u914d\u4fe1\u30b5\u30fc\u30d3\u30b9\u63d0\u4f9b\u4f1a\u793e \u69d8"}]},{"@type":"WebSite","@id":"https:\/\/dgloss.co.jp\/#website","url":"https:\/\/dgloss.co.jp\/","name":"DGLOSS Co., Ltd","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dgloss.co.jp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios\/530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios"}],"about":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/types\/portfolios"}],"wp:attachment":[{"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/media?parent=530"}],"wp:term":[{"taxonomy":"portfolios-cat","embeddable":true,"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios-cat?post=530"},{"taxonomy":"portfolios-tag","embeddable":true,"href":"https:\/\/dgloss.co.jp\/en\/wp-json\/wp\/v2\/portfolios-tag?post=530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}